{"id":829,"date":"2012-03-24T09:57:44","date_gmt":"2012-03-24T08:57:44","guid":{"rendered":"http:\/\/www.claudia-klinger.de\/digidiary\/?p=829"},"modified":"2012-03-24T11:31:25","modified_gmt":"2012-03-24T10:31:25","slug":"morgenlektuere-querbeet","status":"publish","type":"post","link":"https:\/\/www.claudia-klinger.de\/digidiary\/2012\/03\/24\/morgenlektuere-querbeet\/","title":{"rendered":"Morgenlekt\u00fcre querbeet"},"content":{"rendered":"<p><strong>Thinkabout<\/strong> berichtet Erhellendes \u00fcber den <a href=\"http:\/\/thinkabout.ch\/article\/die-usa-ganz-mau-legal-zum-datenklau\">\u00dcberwachungswahn der USA<\/a>: die drohen den Staaten mit Einf\u00fcrung einer Visumspflicht, wenn ein neues (in der Regel unk\u00fcndbares!) Abkommen nicht unterzeichnet wird, das auch Verm\u00f6gensausk\u00fcnfte \u00fcber die Einreisenden umfasst. Fr\u00fcher hatte ich vor, die USA mal zu besuchen, diese Idee hab ich lange schon aufgegeben! <!--more--><\/p>\n<p>*<\/p>\n<p>Stirbt das Land vor Langeweile? fragt <strong>Malte Wedding<\/strong> in einer fulminanten <a href=\"http:\/\/www.berliner-zeitung.de\/magazin\/essay-zum-deutschen-fernsehen-stirbt-das-land-vor-langeweile-,10809156,11953168.html\">Brandrede gegen die \u00d6dnis des deutschen Fernsehens<\/a>. Da ich im letzten Winter mehr TV geschaut habe als sonst, kann ich ihm nur zustimmen! <\/p>\n<p>*<\/p>\n<p><strong>Christa<\/strong> hat sich von den Such-Begriffen, \u00fcber die Leser auf ihr ver-rueckt.net finden, inspirieren lassen und einen <a href=\"http:\/\/ver-rueckt.net\/?p=7279\">Artikel \u00fcber ihre 38-j\u00e4hrige Ehe<\/a> (Respekt!) geschrieben. <\/p>\n<p>*<\/p>\n<p><a href=\"http:\/\/theintelligence.de\/index.php\/gesellschaft\/soziales\/4185-vier-hindernisse-am-weg-zur-objektivitaet.html\">Vier Hindernisse am Weg zur Objektivit\u00e4t<\/a> beschreibt <strong>Konrad Mausner<\/strong> auf TheIntelligenz. &#8222;Was h\u00e4lt so viele Menschen davon ab, sowohl absolut logische Schl\u00fcsse als auch belegbare Fakten zu akzeptieren?&#8220; &#8211; spannend!<\/p>\n<p>*<\/p>\n<p>Ebenfalls auf TheIntelligenz: ein Blick in die Zukunft der <a href=\"http:\/\/theintelligence.de\/index.php\/politik\/kommentare\/4175-staatlich-gefoerderte-hochleistungs-rentner.html\">staatlich gef\u00f6rderten Hochleistungsrentner<\/a> &#8211; die Zuverdienstregelung soll drastisch ge\u00e4ndert werden, <strong>Walter Klotz<\/strong> referiert die Auswirkungen. <\/p>\n<p>*<\/p>\n<p><strong>Eva Schumann<\/strong> entdeckt nach Jahre langere Abstinenz das <a href=\"http:\/\/www.tinto.de\/tipps\/zeitunglesen-zur-entschleunigung\/\">Zeitunglesen zur Entschleunigung<\/a>. Damit hab&#8216; ich auch schon gelieb\u00e4ugelt, sehe aber momentan nicht, wie ich das zeitlich unterbringen k\u00f6nnte&#8230; :-)<\/p>\n<p>***<br \/>\nUpdate: Ach ja, gebloggt hab&#8216; ich auch schon: n\u00e4mlich \u00fcber <a href=\"http:\/\/www.unverbissen-vegetarisch.de\/2012\/03\/post-vegane-erschoepfung-und-ein-unverbissenes-buchprojekt\/\">Post-vegane Ersch\u00f6pfung \u2013 und ein \u201cunverbissenes\u201d Buchprojekt.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Thinkabout berichtet Erhellendes \u00fcber den \u00dcberwachungswahn der USA: die drohen den Staaten mit Einf\u00fcrung einer Visumspflicht, wenn ein neues (in der Regel unk\u00fcndbares!) Abkommen nicht unterzeichnet wird, das auch Verm\u00f6gensausk\u00fcnfte \u00fcber die Einreisenden umfasst. Fr\u00fcher hatte ich vor, die USA mal zu besuchen, diese Idee hab ich lange schon aufgegeben!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts\/829"}],"collection":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/comments?post=829"}],"version-history":[{"count":0,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts\/829\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/media?parent=829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/categories?post=829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/tags?post=829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}