{"id":3123,"date":"2020-08-11T12:52:39","date_gmt":"2020-08-11T10:52:39","guid":{"rendered":"https:\/\/www.claudia-klinger.de\/digidiary\/?p=3123"},"modified":"2020-08-11T12:59:22","modified_gmt":"2020-08-11T10:59:22","slug":"welt-aus-den-fugen","status":"publish","type":"post","link":"https:\/\/www.claudia-klinger.de\/digidiary\/2020\/08\/11\/welt-aus-den-fugen\/","title":{"rendered":"Welt aus den Fugen"},"content":{"rendered":"<p>Lukaschenko l\u00e4sst das Volk pr\u00fcgeln, Erdogan sendet Kriegsschiffe ins Mittelmeer, Beirut liegt in Tr\u00fcmmern, Trump will sein Gesicht am Mount Rushmore sehen. Seehofer verbietet St\u00e4dten die Aufnahme von Fl\u00fcchtlingen. <\/p>\n<p>In Deutschland ist wieder Hei\u00dfzeit, die D\u00fcrre im Norden geht ins 3.Jahr. In ersten Gemeinden wird das Trinkwasser knapp. In der Arktis Hitzerekorde, ausufernde Br\u00e4nde und massiver Eisschwund. Seit Anfang Juli brennen in Russland 1,9 Millionen Hektar Wald, die meisten in Sibirien. Auch am Amazonas brennt der Regenwald heftiger als 2019, es wird mehr illegal gerodet als je zuvor. In Equador bricht eine Pipeline und verseucht mehrere Fl\u00fcsse, in Mauritius havariert ein \u00d6lfrachter vor dem Naturschutzgebiet. Das letzte intakte Schelfeis-Feld in Kanada ist auseinandergebrochen, eine 80 Quadratkilometer gro\u00dfe Eisplatte treibt jetzt vor der K\u00fcste. <\/p>\n<p>Und sonst so? Der Aggressionspegel steigt, auf der Stra\u00dfe, in den L\u00e4den, in den (a-)sozialen Medien, sogar auf Mitgliederversammlungen der Kleingartenvereine. Corona-Maskenstreit, Genervtheit wegen Hitze, Streit ums \u00f6ffentliche Stra\u00dfenland und \u00fcber die Definitionsmacht in Sachen Rassismus.<br \/>\nAn Wochenend-N\u00e4chten Partys im Park, ohne Abstand, ohne Masken, bis zum Polizeieinsatz. <\/p>\n<p>Dass es mir gut geht wundert mich immer \u00f6fter. <\/p>","protected":false},"excerpt":{"rendered":"<p>Lukaschenko l\u00e4sst das Volk pr\u00fcgeln, Erdogan sendet Kriegsschiffe ins Mittelmeer, Beirut liegt in Tr\u00fcmmern, Trump will sein Gesicht am Mount Rushmore sehen. Seehofer verbietet St\u00e4dten die Aufnahme von Fl\u00fcchtlingen. In Deutschland ist wieder Hei\u00dfzeit, die D\u00fcrre im Norden geht ins 3.Jahr. In ersten Gemeinden wird das Trinkwasser knapp. In der Arktis Hitzerekorde, ausufernde Br\u00e4nde und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts\/3123"}],"collection":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/comments?post=3123"}],"version-history":[{"count":0,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts\/3123\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/media?parent=3123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/categories?post=3123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/tags?post=3123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}