{"id":2868,"date":"2019-08-05T12:17:35","date_gmt":"2019-08-05T10:17:35","guid":{"rendered":"https:\/\/www.claudia-klinger.de\/digidiary\/?p=2868"},"modified":"2019-08-05T14:11:59","modified_gmt":"2019-08-05T12:11:59","slug":"blogroll-was-raus-musste-und-was-rein-kam","status":"publish","type":"post","link":"https:\/\/www.claudia-klinger.de\/digidiary\/2019\/08\/05\/blogroll-was-raus-musste-und-was-rein-kam\/","title":{"rendered":"Blogroll: was raus musste und was rein kam"},"content":{"rendered":"<p>Heute hab&#8216; ich mal wieder meine vier Blogbibliotheken gesichtet und einige \u00c4nderungen vorgenommen. Das interessiert vermutlich kaum jemanden, aber ich schreib&#8216; es trotzdem auf. Ein bisschen Linkliebe verstreuen ist auch nie falsch!<!--more--><\/p>\n<ul>\n<li>Im Sektor <a href=\"https:\/\/www.claudia-klinger.de\/digidiary\/blogbibliothek-weltgeschehen\/\">Politik und Weltgeschehen<\/a> musste <a href=\"https:\/\/kaffeeundkapital.de\/\">Kaffe &#038; Kapital<\/a> weichen. Das war mal eine engagierte Publikation (&#8222;Ein \u00f6ffentliches Gespr\u00e4ch zu unserer Demokratie&#8220;), doch mittlerweile tourt der Macher mit Team lieber im &#8222;Real Life&#8220; durch die Lande und wirbt f\u00fcr mehr Klimaschutz. Auch gut, aber f\u00fcr Lesewillige eher nichts. <\/li>\n<li>Hinzu gekommen ist das <a href=\"http:\/\/www.migazin.de\/\">MigMagazin<\/a> (Migration in Germany) und <a href=\"https:\/\/www.proasyl.de\/\">ProAsyl<\/a> (Der Einzelfall z\u00e4hlt). Auch wenn man \u00fcber <a href=\"https:\/\/www.claudia-klinger.de\/digidiary\/2019\/08\/04\/fuer-hassfreie-vernuenftige-debatten-auch-ueber-kriminalitaet-bei-migranten\/\">problematische Aspekte der Integration von Fl\u00fcchtlingen und Migranten<\/a> nicht (mehr) hinweg sieht, bleibt es wichtig, diese Berichte zum realen Geschehen zu lesen und sein Herz nicht einfach zu verschlie\u00dfen! Zudem erf\u00e4hrt man so Details zum Wirken unserer Institutionen, auf die nicht kommen w\u00fcrde, wer sich auf g\u00e4ngige Medien beschr\u00e4nkt. So ist es mir gerade beim Artikel zum <a href=\"https:\/\/www.proasyl.de\/news\/es-gibt-kein-wirklich-geregeltes-verfahren-beim-familiennachzug-herrscht-chaos\/\">Chaos im Familiennachzug<\/a> gegangen. Da treffen die Restriktionen nicht etwa &#8222;nur&#8220; Fl\u00fcchtlinge, die ihre Familie nachholen wollen, sondern auch Deutsche, die im Ausland heiraten. <\/li>\n<li>\nIm Bereich <a href=\"https:\/\/www.claudia-klinger.de\/digidiary\/blogbibliothek-teil-2\/\">Philosophie<\/a> ist das <a href=\"https:\/\/totenhemd.wordpress.com\/\">Totenhemd-Blog<\/a> (\u00dcbers Sterben reden) k\u00fcrzlich dazu gekommen. Zitat: <\/p>\n<blockquote><p>&#8222;&#8230;die meisten Leute, die wir kennen, sind beim Thema Endlichkeit, Sterben, Trauern eher reserviert und irritiert. Das finden wir schade. Und haben Lust, mit unseren Gedanken, Erfahrungen und Experimenten, andere zum Nachdenken und Sprechen \u00fcber \u201edie letzten Dinge\u201c zu verlocken.&#8220;<\/p><\/blockquote>\n<\/li>\n<li>Unter &#8222;<a href=\"https:\/\/www.claudia-klinger.de\/digidiary\/meine-blog-bibliothek\/\">Vermischtes, pers\u00f6nliche Blogs<\/a>&#8220; ist das Blog <a href=\"https:\/\/gemeinsamleben.wordpress.com\/\">Gemeinsamleben<\/a> von Menachem wieder dabei, der nach langer Pause wieder schreibt. Finde ich toll, vor allem, weil er aus der Mitte des AFD-Hypes im Osten berichtet &#8211; und es kaum aush\u00e4lt, was er da so erlebt. Zum Beispiel &#8222;<a href=\"https:\/\/gemeinsamleben.wordpress.com\/2019\/07\/29\/und-jetzt\/\">an der Tanke<\/a>&#8222;. Ich w\u00fcnsche mir mehr Berichte aus erster Hand und w\u00fcsste gerne, was die Leute tats\u00e4chlich motiviert, dem rechtsradikalen &#8222;Fl\u00fcgel&#8220; der AFD zu huldigen!<\/li>\n<\/ul>\n<p>Vorschl\u00e4ge f\u00fcr Blogs, die in die 4 Blogbibliotheken passen w\u00fcrden, nehme ich gerne entgegen!<\/p>\n<p><strong>Update:<\/strong> Grade hab&#8216; ich auch noch das Blog von Solminore ins &#8222;Vermischte&#8220; aufgenommen. <a href=\"https:\/\/askionkataskion.antville.org\/\">VOCES INTIMAE<\/a>, mal reingelesen &#8211; gef\u00e4llt!<\/p>","protected":false},"excerpt":{"rendered":"<p>Heute hab&#8216; ich mal wieder meine vier Blogbibliotheken gesichtet und einige \u00c4nderungen vorgenommen. Das interessiert vermutlich kaum jemanden, aber ich schreib&#8216; es trotzdem auf. Ein bisschen Linkliebe verstreuen ist auch nie falsch!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,7,414],"tags":[],"class_list":["post-2868","post","type-post","status-publish","format-standard","hentry","category-buecher-tipps","category-netzwelt-bloggen-webdesign","category-schreiben-bloggen"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts\/2868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/comments?post=2868"}],"version-history":[{"count":0,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts\/2868\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/media?parent=2868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/categories?post=2868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/tags?post=2868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}