{"id":2691,"date":"2018-11-26T17:59:04","date_gmt":"2018-11-26T16:59:04","guid":{"rendered":"https:\/\/www.claudia-klinger.de\/digidiary\/?p=2691"},"modified":"2018-11-29T11:32:41","modified_gmt":"2018-11-29T10:32:41","slug":"klassenkampf-von-oben-geht-doch-backen-nachts-um-halb-eins","status":"publish","type":"post","link":"https:\/\/www.claudia-klinger.de\/digidiary\/2018\/11\/26\/klassenkampf-von-oben-geht-doch-backen-nachts-um-halb-eins\/","title":{"rendered":"Klassenkampf von oben: Geht doch backen nachts um halb eins!"},"content":{"rendered":"<p>Da sitzen sie also zusammen bei Anne Will und diskutieren, wie es mit den zu Recht in Verruf geratenen Hartz4-Sanktionen weiter gehen soll:<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/VECaBORQdSs?start=8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<ul>\n<li><strong>Jens Spahn<\/strong> (Gesundheitsminister) steht zum derzeitigen System und will h\u00f6chstens bei 57plus ein wenig moderater werden beim &#8222;Fordern&#8220;.<\/li>\n<li><strong>Lars Klingbeil<\/strong> (SPD-Generalsekret\u00e4r \/ Seeheimer Kreis) prophezeit riesige Jobverluste durch Digitalisierung, will aber nur hier und da ein bisschen B\u00fcrokratie abbauen, vielleicht in einigen H\u00e4rtef\u00e4llen und bei Jugendlichen etwas weniger sanktionieren, ist aber ansonsten mit Spahn (&#8222;Druck erhalten&#8220;) recht einig.<\/li>\n<li>Die Abschaffung von Hartz4 fordert\u00a0<strong>Sahra Wagenknecht<\/strong> (Die Linke), die das immer wieder zitierte &#8222;Lohnabstandsgebot&#8220; durch h\u00f6here Mindestl\u00f6hne erreichen will. Dass Menschen gezwungen w\u00fcrden, unterbezahlte Jobs und sogar Leiharbeit anzunehmen, habe zu einem riesigen Niedriglohnsektor gef\u00fchrt. Denn nach Hartz4 sei &#8222;zumutbare Arbeit&#8220; &#8211; anders als fr\u00fcher &#8211; heute &#8222;jede Art Arbeit&#8220;, ungeachtet der bisherigen Qualifikationen. Der Staat mache sich so mitschuldig an der zunehmenden Tarifflucht und daran, dass viele von ihrem Einkommen nicht mehr Leben k\u00f6nnen und keine ausk\u00f6mmlichen Renten entstehen.<\/li>\n<li>Noch radikaler dann <strong>Michael Bohmeyer<\/strong> vom Verein <a href=\"https:\/\/www.mein-grundeinkommen.de\/\">&#8222;Mein Grundeinkommen&#8220;<\/a>: Er schw\u00e4rmt vom motivierenden Schub, den ein bedingungsloses Grundeinkommen f\u00fcr Arbeitende wie Arbeitslose bedeute: Wer sich abgesichert f\u00fchle, mache sich daran, in einer selbst gew\u00e4hlten Arbeit oder Selbstst\u00e4ndigkeit zwanglos Einkommen zu erwirtschaften.<\/li>\n<\/ul>\n<p><!--more--><\/p>\n<p>Dass dann auch noch die als &#8222;Frau der Wirtschaft&#8220; geladene Unternehmensberaterin <a href=\"https:\/\/de.wikipedia.org\/wiki\/Simone_Menne\"><strong>Simone Menne<\/strong><\/a> den radikalen Schnitt und eine beherzte Neuorientierung des Sozialsystems verlangt, kommt aber doch etwas \u00fcberraschend. Anne Will bringt erstmal brav die Dinge auf den Punkt, indem sie ausf\u00fchrt:<\/p>\n<blockquote><p>&#8222;Die Wirtschaft hat massiv davon profitiert, dass Menschen \u00fcber das alte Hartz4-System gezwungen waren und noch gezwungen sind, jeden Job anzunehmen. Warum sollte man so ein Erfolgsmodell \u00e4ndern?&#8220;<\/p><\/blockquote>\n<p>Menne holt dazu etwas weiter aus und spricht \u00fcber die disruptiven \u00c4nderugen, mit denen die Unternehmen sich zunehmend konfrontiert sehen. Die Gesellschaft m\u00fcsse sich ebenso radikal ver\u00e4ndern, wie es von den Unternehmen verlangt werde, denen ganze Gesch\u00e4ftsfelder durch die Digitalisierung wegbrechen. Die Sozialsysteme m\u00fcssten komplett neu gedacht werden, nicht nur ein wenig am Vorhandenen herumgeklittert. Bildung, und zwar lebenslange Bildung sei extrem wichtig, und weiter:<\/p>\n<blockquote><p>&#8222;Wie schaffen wir es, m\u00f6glichst viele Menschen in die Erwerbst\u00e4tigkeit zu bekommen? Auch da bin ich eher ein Freund der Motivation als einer Ausgestaltung von Modellen, die am Missbrauch ausgerichtet sind und alles tun, um den, der missbraucht, gang ganz wasserdicht davon abzuhalten. Wir haben auch Steuerbetr\u00fcger, die aus gr\u00f6\u00dferen Einkommensschichten&#8230;&#8220; <span style=\"font-style: normal;\">(bricht hier ab, Anne Will grinst verst\u00e4ndnisinnig, Publikum applaudiert).<\/span><\/p><\/blockquote>\n<h2>Sanktionen in Gefahr? Da sei der B\u00e4ckermeister vor!<\/h2>\n<p>Angesichts von so viel verst\u00e4ndnisvoller Kritik am herrschenden Sanktionsregime z\u00fcckt Anne Will nun die Wunderwaffe &#8222;echtes Leben&#8220;. Per Einspieler tritt auf <a href=\"http:\/\/www.dresdner-feinbaeckerei.de\/start.html#\">B\u00e4ckermeister Schwadtke aus Berlin Friedrichshagen<\/a>, der nachts um halb eins in der Backstube steht und mit seinen Gesellen den Brotteig in Form bringt. Seit zwei Jahren hat die Backstube Montags geschlossen, weil sich nicht genug Arbeitskr\u00e4fte finden, um durchzuarbeiten. Schwadtke beklagt, dass die vom Jobcenter vermittelten Arbeitslosen zwar zum halbst\u00fcndigen Erstgespr\u00e4ch k\u00e4men, dann aber nicht mehr. Und klar, er stehe voll hinter den Sanktionen, denn er und seine Leute arbeiteten ja nachts und zahlten auch Steuern. Kann doch nicht funktionieren, wenn die sich da ausruhen&#8230;<\/p>\n<p>Anne Will hinterfragt nun bei Sahra Wagenknecht, warum der B\u00e4ckermeister eigentlich eine ohne Sanktionsdrohung gezahlte Grundsicherung von 1050 Euro fair finden solle. Wagenknechts Antwort, dass der B\u00e4ckerjob als ziemlich harte Arbeit deutlich besser bezahlt geh\u00f6re, reicht ihr nat\u00fcrlich nicht. <strong>Will streitet jetzt geradezu begeistert daf\u00fcr, dass das &#8222;Backen nachts um halb eins&#8220; doch eine zumutbare Arbeit sei.<\/strong> Und da der B\u00e4ckermeister im Publikum anwesend ist, erfahren wir auch noch, dass er \u00fcbertariflich bezahlt, sogar mehr als 12 Euro, den von der Linken geforderten Mindestlohn.<\/p>\n<p>Tja, was nun? Das k\u00f6nnen ja wirklich nur b\u00f6se b\u00f6se Faulenzer und Sozialschmarotzer sein, die so einen Traumjob nicht mit Kusshand annehmen! Das ist es doch, was hier in die K\u00f6pfe gedr\u00fcckt werden soll, und was Anne Will am best bezahlten Talk-Sendeplatz der Republik h\u00f6chstens denken, aber nicht so deutlich sagen darf.<\/p>\n<p>Jens Spahn nutzt die Gunst der Stunde und gibt dem Thema einen Dreh, mit dem er der Wagenknecht nochmal so richtig einschenken will. F\u00fcr wen es denn nicht zumutbar sei, in der Backstube zu arbeiten, will er nun genau wissen (<em>Anne Will BEDANKT sich aus dem Hintergrund bei ihm, dass er das nachfragt!<\/em>). Und als Sahra antwortet, z.B. f\u00fcr einen Ingenieur sei die B\u00e4ckerei nicht das passende Bet\u00e4tigungsfeld, wirft er ihr vor, dass sie Handwerksarbeit offenbar f\u00fcr Akademiker grunds\u00e4tzlich als &#8222;Deklassierung&#8220; betrachte. Ihren Hinweis, auch f\u00fcr ausgebildete Handwerker sei nicht jeder Job zumutbar, man verliere ja auch auf Dauer seine Qualifikation, nimmt er schon gar nicht mehr ernst. Sondern freut sich sichtlich \u00fcber die vermeintliche Entlarvung eines Akademikerd\u00fcnkels bei Wagenknecht. Anne Will und Jens Spahn, vereint im Klassenkampf von oben nach unten, assistiert vom B\u00e4ckermeister aus Friedrichshagen, der meint, sein Job sei doch wunderbar, denn morgens um 8 liege ja der ganze Tag noch vor einem!<\/p>\n<h2>Klassenkampf: Oben wird abgesahnt, unten sanktioniert<\/h2>\n<p>Menschen wie Spahn loben ja den &#8222;Erfolg&#8220; der Agenda 2010 immer gern \u00fcber den gr\u00fcnen Klee. Was bei aller Freude \u00fcber die gestiegene Erwerbsarbeit, die gesunkenen L\u00f6hne und den prek\u00e4ren Billiglohnsektor nat\u00fcrlich nie zur Sprache kommt:\u00a0 wenns knirscht und holpert im Wirtschaftsgeb\u00e4ude Deutschland, sind es nie die Wills und Spahns, die den G\u00fcrtel enger schnallen. Sondern es wird unten und in der Mitte gespart, gestrichen, gefordert und alles Erdenkliche zugemutet, was fr\u00fcher indiskutabel war, sogar bei der CDU.<\/p>\n<p>Deshalb wird mir richtig schlecht, wenn ich ihnen bei einem solchen Thema zuh\u00f6re. Diese Ignoranz gegen\u00fcber den Lebensinteressen \u00e4rmerer Menschen, die nicht mal die &#8222;Frau aus der Wirtschaft&#8220; teilt, ist an sich schon skandal\u00f6s, aber hierzulande (immer wieder das Land besonders braver Untertanen).leider so normal. Da kann im Wochentakt ein <a href=\"https:\/\/www.tagesschau.de\/wirtschaft\/cum-cum-105.html\">Mega-Steuerskandal<\/a> nach <a href=\"https:\/\/www.handelsblatt.com\/politik\/deutschland\/adr-aktien-moeglicher-neuer-steuerskandal-um-phantom-papiere\/23665138.html\">dem Anderen<\/a> auffliegen, nichts macht offenbar so sehr Spass wie das Herumhacken auf Arbeitslosen, von denen einige wenige tats\u00e4chlich nicht &#8222;kooperieren&#8220;, Termine vers\u00e4umen oder sich gar erdreisten, nicht nachts um halb eins Br\u00f6tchen backen zu wollen.<\/p>\n<p>Ein Handwerk \u00fcbrigens, das sich extrem im Umbruch befindet, das <a href=\"https:\/\/www.baeckerhandwerk.de\/baeckerhandwerk\/zahlen-fakten\/\">seit Jahren schrumpft<\/a> und ganz gewiss nicht von Zwangsarbeitern gerettet wird! Sondern\u00a0 &#8211; in kleinerem Rahmen &#8211; von leidenschaftlichen &#8222;<a href=\"https:\/\/www.tip-berlin.de\/berlins-beste-baecker\/\">neuen B\u00e4ckern<\/a>&#8222;, die sich mit viel Kreativit\u00e4t der deutschen Brotkultur widmen, die mittlerweile Weltkulturerbe ist. Aber davon dann ein andermal.<\/p>","protected":false},"excerpt":{"rendered":"<p>Da sitzen sie also zusammen bei Anne Will und diskutieren, wie es mit den zu Recht in Verruf geratenen Hartz4-Sanktionen weiter gehen soll: Jens Spahn (Gesundheitsminister) steht zum derzeitigen System und will h\u00f6chstens bei 57plus ein wenig moderater werden beim &#8222;Fordern&#8220;. Lars Klingbeil (SPD-Generalsekret\u00e4r \/ Seeheimer Kreis) prophezeit riesige Jobverluste durch Digitalisierung, will aber nur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,231],"tags":[],"class_list":["post-2691","post","type-post","status-publish","format-standard","hentry","category-wirtschaft-gesellschaft-politik","category-zeitgeist"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts\/2691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/comments?post=2691"}],"version-history":[{"count":0,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/posts\/2691\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/media?parent=2691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/categories?post=2691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.claudia-klinger.de\/digidiary\/wp-json\/wp\/v2\/tags?post=2691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}